
    <div class="lsform-form-wrap hanor-lsform-6a97cd5bd34f7 signup-form ">
      
  <form name="loginform" id="loginform" action="https://victorthemes.com/themes/havnor/logistic/wp-json/wp/v2/pages/827" method="post">
    <div class="row">
      <div class="col-sm-6">
        <p>
          <input name="email" id="email_address" class="input" placeholder="Email" size="20" type="email" value="">
        </p>
      </div>
      <div class="col-sm-6">
        <p>
          <input name="password" id="password" class="input" placeholder="Password" size="20" type="password" value="">
        </p>
      </div>
      <div class="col-sm-12">
        <p>
          <input name="first_name" id="full_name" class="input" placeholder="Your Name" size="20" type="text" value="">
        </p>
      </div>
      <div class="col-sm-12 text-center">
        <p>
          <input name="wp-submit" id="wp-submit" class="" value="Create Account" type="submit">
          <input name="redirect_to" value="" type="hidden">
        </p>
      </div>
    </div>
  </form>
      </div>
{"id":827,"date":"2018-07-17T12:20:38","date_gmt":"2018-07-17T12:20:38","guid":{"rendered":"https:\/\/victorthemes.com\/themes\/havnor\/logistic\/?page_id=827"},"modified":"2018-07-17T12:23:18","modified_gmt":"2018-07-17T12:23:18","slug":"signup","status":"publish","type":"page","link":"https:\/\/victorthemes.com\/themes\/havnor\/logistic\/signup\/","title":{"rendered":"SignUp"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][\/vc_column][\/vc_row]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/victorthemes.com\/themes\/havnor\/logistic\/wp-json\/wp\/v2\/pages\/827"}],"collection":[{"href":"https:\/\/victorthemes.com\/themes\/havnor\/logistic\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/victorthemes.com\/themes\/havnor\/logistic\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/victorthemes.com\/themes\/havnor\/logistic\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/victorthemes.com\/themes\/havnor\/logistic\/wp-json\/wp\/v2\/comments?post=827"}],"version-history":[{"count":2,"href":"https:\/\/victorthemes.com\/themes\/havnor\/logistic\/wp-json\/wp\/v2\/pages\/827\/revisions"}],"predecessor-version":[{"id":829,"href":"https:\/\/victorthemes.com\/themes\/havnor\/logistic\/wp-json\/wp\/v2\/pages\/827\/revisions\/829"}],"wp:attachment":[{"href":"https:\/\/victorthemes.com\/themes\/havnor\/logistic\/wp-json\/wp\/v2\/media?parent=827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}